{"id":13382,"date":"2023-11-14T16:07:22","date_gmt":"2023-11-14T10:37:22","guid":{"rendered":"https:\/\/whitehats.tech\/INDIA\/?page_id=13382"},"modified":"2024-02-13T14:31:10","modified_gmt":"2024-02-13T09:01:10","slug":"sebi-compliance","status":"publish","type":"page","link":"https:\/\/whitehats.tech\/INDIA\/sebi-compliance\/","title":{"rendered":"SEBI Compliance\u200b"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13382\" class=\"elementor elementor-13382\">\n\t\t\t\t\t\t<header class=\"elementor-section elementor-top-section elementor-element elementor-element-01b8453 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"01b8453\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9336c45\" data-id=\"9336c45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1de67b1 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"1de67b1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8c73500\" data-id=\"8c73500\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0462e4 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"b0462e4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"424\" height=\"102\" src=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/whitehats-logo-1.webp\" class=\"attachment-medium_large size-medium_large wp-image-13764\" alt=\"\" srcset=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/whitehats-logo-1.webp 424w, https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/whitehats-logo-1-300x72.webp 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-21061c3\" data-id=\"21061c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0747cc wpr-main-menu-align-right wpr-main-menu-align--tabletcenter wpr-nav-menu-bp-tablet elementor-widget-tablet__width-initial wpr-mobile-menu-custom-width wpr-mobile-menu-drdown-align-right elementor-widget__width-initial wpr-main-menu-align--mobileleft wpr-pointer-underline wpr-pointer-line-fx wpr-pointer-fx-fade wpr-sub-icon-caret-down wpr-sub-menu-fx-fade wpr-mobile-menu-item-align-center wpr-mobile-toggle-v1 wpr-sub-divider-yes wpr-mobile-divider-yes elementor-widget elementor-widget-wpr-nav-menu\" data-id=\"f0747cc\" data-element_type=\"widget\" data-settings=\"{&quot;menu_layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"wpr-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<nav class=\"wpr-nav-menu-container wpr-nav-menu-horizontal\" data-trigger=\"hover\"><ul id=\"menu-1-f0747cc\" class=\"wpr-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-13369\"><a href=\"https:\/\/whitehats.tech\/INDIA\/\" class=\"wpr-menu-item wpr-pointer-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-13078\"><a href=\"#about\" class=\"wpr-menu-item wpr-pointer-item\">About<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-3923\"><a href=\"\" class=\"wpr-menu-item wpr-pointer-item\">Product<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-13753\"><a href=\"https:\/\/www.whitehats.tech\/US\/data-security\/\" class=\"wpr-sub-menu-item\">Data Foresight<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-13752\"><a href=\"https:\/\/whitehats.tech\/US\/grc\/\" class=\"wpr-sub-menu-item\">Compliance Foresight<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15760\"><a href=\"https:\/\/whitehats.tech\/INDIA\/saas-grc\/\" class=\"wpr-sub-menu-item\">Saas Model<i class=\"wpr-sub-icon fas wpr-sub-icon-rotate\" aria-hidden=\"true\"><\/i><\/a>\n\t<ul class=\"sub-menu wpr-sub-menu\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14772\"><a href=\"https:\/\/whitehats.tech\/INDIA\/on-demand-application-security\/\" class=\"wpr-sub-menu-item\">ODAS<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15819\"><a href=\"https:\/\/whitehats.tech\/INDIA\/audit-management\/\" class=\"wpr-sub-menu-item\">Audit Management<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14892\"><a href=\"https:\/\/whitehats.tech\/INDIA\/compliance-management\/\" class=\"wpr-sub-menu-item\">Policy Management<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15128\"><a href=\"https:\/\/whitehats.tech\/INDIA\/integrated-vulnerability-management\/\" class=\"wpr-sub-menu-item\">Vulnerability Management<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-home menu-item-has-children menu-item-13080\"><a href=\"https:\/\/whitehats.tech\/INDIA\" class=\"wpr-menu-item wpr-pointer-item\">Compliances<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13319\"><a href=\"https:\/\/whitehats.tech\/INDIA\/iso-27001-2022\/\" class=\"wpr-sub-menu-item\">ISO 27001:2022\u00a0<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13206\"><a href=\"https:\/\/whitehats.tech\/INDIA\/iso-27701\/\" class=\"wpr-sub-menu-item\">ISO 27701<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13362\"><a href=\"https:\/\/whitehats.tech\/INDIA\/iso-22301\/\" class=\"wpr-sub-menu-item\">ISO 22301<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13366\"><a href=\"https:\/\/whitehats.tech\/INDIA\/irda-compliance\/\" class=\"wpr-sub-menu-item\">IRDA Compliance<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13421\"><a href=\"https:\/\/whitehats.tech\/INDIA\/sebi-compliance\/\" class=\"wpr-sub-menu-item\">SEBI Compliance\u200b<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-14077\"><a href=\"#contact\" class=\"wpr-menu-item wpr-pointer-item\">Contact<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-13427\"><a href=\"https:\/\/whitehats.tech\/INDIA\/event\/\" class=\"wpr-menu-item wpr-pointer-item\">News<\/a><\/li>\n<\/ul><\/nav><nav class=\"wpr-mobile-nav-menu-container\"><div class=\"wpr-mobile-toggle-wrap\"><div class=\"wpr-mobile-toggle\"><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><\/div><\/div><ul id=\"mobile-menu-2-f0747cc\" class=\"wpr-mobile-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-13369\"><a href=\"https:\/\/whitehats.tech\/INDIA\/\" class=\"wpr-mobile-menu-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-13078\"><a href=\"#about\" class=\"wpr-mobile-menu-item\">About<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-3923\"><a class=\"wpr-mobile-menu-item\">Product<\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-13753\"><a href=\"https:\/\/www.whitehats.tech\/US\/data-security\/\" class=\"wpr-mobile-sub-menu-item\">Data Foresight<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-13752\"><a href=\"https:\/\/whitehats.tech\/US\/grc\/\" class=\"wpr-mobile-sub-menu-item\">Compliance Foresight<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15760\"><a href=\"https:\/\/whitehats.tech\/INDIA\/saas-grc\/\" class=\"wpr-mobile-sub-menu-item\">Saas Model<\/a>\n\t<ul class=\"sub-menu wpr-sub-menu\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14772\"><a href=\"https:\/\/whitehats.tech\/INDIA\/on-demand-application-security\/\" class=\"wpr-mobile-sub-menu-item\">ODAS<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15819\"><a href=\"https:\/\/whitehats.tech\/INDIA\/audit-management\/\" class=\"wpr-mobile-sub-menu-item\">Audit Management<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14892\"><a href=\"https:\/\/whitehats.tech\/INDIA\/compliance-management\/\" class=\"wpr-mobile-sub-menu-item\">Policy Management<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15128\"><a href=\"https:\/\/whitehats.tech\/INDIA\/integrated-vulnerability-management\/\" class=\"wpr-mobile-sub-menu-item\">Vulnerability Management<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-home menu-item-has-children menu-item-13080\"><a href=\"https:\/\/whitehats.tech\/INDIA\" class=\"wpr-mobile-menu-item\">Compliances<\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13319\"><a href=\"https:\/\/whitehats.tech\/INDIA\/iso-27001-2022\/\" class=\"wpr-mobile-sub-menu-item\">ISO 27001:2022\u00a0<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13206\"><a href=\"https:\/\/whitehats.tech\/INDIA\/iso-27701\/\" class=\"wpr-mobile-sub-menu-item\">ISO 27701<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13362\"><a href=\"https:\/\/whitehats.tech\/INDIA\/iso-22301\/\" class=\"wpr-mobile-sub-menu-item\">ISO 22301<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13366\"><a href=\"https:\/\/whitehats.tech\/INDIA\/irda-compliance\/\" class=\"wpr-mobile-sub-menu-item\">IRDA Compliance<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13421\"><a href=\"https:\/\/whitehats.tech\/INDIA\/sebi-compliance\/\" class=\"wpr-mobile-sub-menu-item\">SEBI Compliance\u200b<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-14077\"><a href=\"#contact\" class=\"wpr-mobile-menu-item\">Contact<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-13427\"><a href=\"https:\/\/whitehats.tech\/INDIA\/event\/\" class=\"wpr-mobile-menu-item\">News<\/a><\/li>\n<\/ul><\/nav>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-addce2f\" data-id=\"addce2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8af310 elementor-align-left elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"d8af310\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/whitehats.tech\/INDIA\/get-a-demo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get a Demo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ef0ebb3\" data-id=\"ef0ebb3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12fc604 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-shortcode\" data-id=\"12fc604\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"gtranslate_wrapper\" id=\"gt-wrapper-27509325\"><\/div> <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-a685aab\" data-id=\"a685aab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1916a15 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"1916a15\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.whitehats.tech\/US\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/ezgif.com-gif-maker-3.webp\" title=\"WHITEHATS US\" alt=\"WHITEHATS US\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78c37f5e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"78c37f5e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd23c79\" data-id=\"bd23c79\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b7b139 elementor-widget elementor-widget-spacer\" data-id=\"9b7b139\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fc92872 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"5fc92872\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f82a742\" data-id=\"f82a742\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-adc49e3 elementor-widget elementor-widget-heading\" data-id=\"adc49e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">SEBI Compliance<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63e8c41e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"63e8c41e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31c77a20\" data-id=\"31c77a20\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6eea649f elementor-widget elementor-widget-image\" data-id=\"6eea649f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/SEBI-Compliance-1024x576.webp\" class=\"attachment-large size-large wp-image-13727\" alt=\"SEBI Compliance\" srcset=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/SEBI-Compliance-1024x576.webp 1024w, https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/SEBI-Compliance-300x169.webp 300w, https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/SEBI-Compliance-768x432.webp 768w, https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/SEBI-Compliance.webp 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-56789909\" data-id=\"56789909\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46134e7e elementor-widget elementor-widget-text-editor\" data-id=\"46134e7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><strong>SEBI<\/strong> (Securities and Exchange Board of India) has issued various guidelines and regulations related to cybersecurity compliance for the Indian securities market. The SEBI (Listing Obligations and Disclosure Requirements) Regulations, 2015, requires listed companies to adopt adequate cybersecurity measures and disclose the same to the stock exchanges.<\/p>\n<p>SEBI has taken various steps to ensure that the Indian securities market is adequately protected against cyber threats and that all stakeholders in the market are compliant with relevant cybersecurity regulations and guidelines.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-326840ee elementor-widget elementor-widget-button\" data-id=\"326840ee\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"mailto:sales@whitehats.tech\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mail-bulk\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Connect us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77d9483 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"77d9483\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40d79fc6\" data-id=\"40d79fc6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5525f617 elementor-widget elementor-widget-spacer\" data-id=\"5525f617\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70cc12c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"70cc12c1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41a2c24e\" data-id=\"41a2c24e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56ae6cea elementor-widget elementor-widget-heading\" data-id=\"56ae6cea\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/whitehats.in\/global\/wp-content\/uploads\/2023\/04\/DOC-20230403-WA0012.pdf\" target=\"_blank\">SEBI has released the Guidelines for Cyber Security and Cyber Resilience for all organizations registered with SEBI<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e8c40a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"2e8c40a8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a771702\" data-id=\"a771702\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad9d7bf elementor-widget elementor-widget-spacer\" data-id=\"ad9d7bf\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6516b9e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"6516b9e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-444996ec\" data-id=\"444996ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f99f9b elementor-widget elementor-widget-heading\" data-id=\"f99f9b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Key provisions and highlights of the\ncyber security and resilience framework<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41341f57 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"41341f57\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b732e1a\" data-id=\"7b732e1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-74cce98e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"74cce98e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-20a90934\" data-id=\"20a90934\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40fe1c0e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"40fe1c0e\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-search\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1438fa6d elementor-widget elementor-widget-heading\" data-id=\"1438fa6d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Identification and Protection Mechanism<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b03ea0e elementor-widget elementor-widget-heading\" data-id=\"6b03ea0e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Establish Governance Framework, Network and Security Controls, Data Security Controls, Application and Infrastructure Security<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c9dec74\" data-id=\"c9dec74\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60ab3558 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"60ab3558\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-users-cog\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c796047 elementor-widget elementor-widget-heading\" data-id=\"2c796047\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Detection and Response Mechanism<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cf03e88 elementor-widget elementor-widget-heading\" data-id=\"5cf03e88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Continuous Monitoring and Reporting, Threat Detection and Analysis, Setting up Alerts Mechanisms <\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3b7da57d\" data-id=\"3b7da57d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bd5be2e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2bd5be2e\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cloud\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b328956 elementor-widget elementor-widget-heading\" data-id=\"3b328956\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Remediation and Recovery<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-606750f2 elementor-widget elementor-widget-heading\" data-id=\"606750f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Create Remediation Priorities, Remediation Mechanisms, Internal and External Audits, BCP\/DR framework and activity<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2402a504 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"2402a504\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11cedaae\" data-id=\"11cedaae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a435a05 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"3a435a05\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6bb1dd89\" data-id=\"6bb1dd89\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80639ab elementor-widget elementor-widget-heading\" data-id=\"80639ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Achieve your Cyber Security Compliance<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9fad696 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"9fad696\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-186ba94e\" data-id=\"186ba94e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c80ef9f elementor-widget elementor-widget-image\" data-id=\"4c80ef9f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/whitehats.tech\/US\/grc\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"120\" src=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/1-300x120.png\" class=\"attachment-medium size-medium wp-image-13118\" alt=\"\" srcset=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/1-300x120.png 300w, https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/1.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1fdc2a0a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"1fdc2a0a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1676a5ad\" data-id=\"1676a5ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b7134aa elementor-widget elementor-widget-spacer\" data-id=\"3b7134aa\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2062ae8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"2062ae8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18a06ebe\" data-id=\"18a06ebe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2282a15d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"2282a15d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3dd2f21b\" data-id=\"3dd2f21b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f1dbcd6 elementor-widget elementor-widget-image\" data-id=\"1f1dbcd6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/4897679-1-150x150.webp\" class=\"attachment-thumbnail size-thumbnail wp-image-13352\" alt=\"\" srcset=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/4897679-1-150x150.webp 150w, https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/4897679-1-300x300.webp 300w, https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/4897679-1.webp 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8a2efe elementor-widget elementor-widget-heading\" data-id=\"b8a2efe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Compliance Management<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-74ec9c22\" data-id=\"74ec9c22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65d7c4dc elementor-widget elementor-widget-image\" data-id=\"65d7c4dc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/png-transparent-security-information-and-event-management-vulnerability-computer-security-threat-others-miscellaneous-text-computer-removebg-preview-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-13353\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-408c9ab elementor-widget elementor-widget-heading\" data-id=\"408c9ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Integrated Vulnerability Management<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5f0c8dbd\" data-id=\"5f0c8dbd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d807206 elementor-widget elementor-widget-image\" data-id=\"1d807206\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/message-privacy-6483638-5373594-150x150.webp\" class=\"attachment-thumbnail size-thumbnail wp-image-13354\" alt=\"\" srcset=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/message-privacy-6483638-5373594-150x150.webp 150w, https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/message-privacy-6483638-5373594-300x300.webp 300w, https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/message-privacy-6483638-5373594.webp 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-646e9bef elementor-widget elementor-widget-heading\" data-id=\"646e9bef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Integrated Privacy Framework<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a980339 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"1a980339\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4d96b4a\" data-id=\"4d96b4a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7445e06f elementor-widget elementor-widget-image\" data-id=\"7445e06f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/download-2-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-13355\" alt=\"\" srcset=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/download-2-150x150.png 150w, https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/download-2.png 224w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52e3375f elementor-widget elementor-widget-heading\" data-id=\"52e3375f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ISO 27001:2022<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-14f521dc\" data-id=\"14f521dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5499f3cd elementor-widget elementor-widget-image\" data-id=\"5499f3cd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/images-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-13356\" alt=\"\" srcset=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/images-150x150.jpg 150w, https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/images.jpg 225w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-613fec1d elementor-widget elementor-widget-heading\" data-id=\"613fec1d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.whitehats.tech\/US\/\">ISO 22301<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-75be09b0\" data-id=\"75be09b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69e17ed0 elementor-widget elementor-widget-image\" data-id=\"69e17ed0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/download-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-13357\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-213f5d48 elementor-widget elementor-widget-heading\" data-id=\"213f5d48\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Risk Management<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a4cca3 envato-kit-141-top-0 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-sticky-section-no\" data-id=\"1a4cca3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-710cdac elementor-invisible\" data-id=\"710cdac\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-320680b elementor-widget elementor-widget-heading\" data-id=\"320680b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONTACT US<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3125aee elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3125aee\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/whitehats.tech\/INDIA\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A - 31, Sector - 4       Noida, UP 201301       India<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:sales@whitehats.tech\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope-open\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">sales@whitehats.tech<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-185bd83 elementor-invisible\" data-id=\"185bd83\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bf8e16 elementor-widget elementor-widget-heading\" data-id=\"9bf8e16\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">USEFUL LINKS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29c0395 eael-hamburger--none elementor-widget-mobile__width-initial eael_simple_menu_hamburger_disable_selected_menu_no eael-simple-menu-hamburger-align-right elementor-widget elementor-widget-eael-simple-menu\" data-id=\"29c0395\" data-element_type=\"widget\" data-widget_type=\"eael-simple-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t            <div data-hamburger-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-bars&quot;&gt;&lt;\/i&gt;\" data-indicator-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" data-dropdown-indicator-icon=\"&lt;i class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" class=\"eael-simple-menu-container eael-simple-menu-align-left eael-simple-menu-dropdown-align-left preset-1\" data-hamburger-breakpoints=\"{&quot;mobile&quot;:&quot;Mobile Portrait (&gt; 767px)&quot;,&quot;tablet&quot;:&quot;Tablet Portrait (&gt; 1024px)&quot;,&quot;desktop&quot;:&quot;Desktop (&gt; 2400px)&quot;,&quot;none&quot;:&quot;None&quot;}\" data-hamburger-device=\"none\">\n                <ul id=\"menu-footer1\" class=\"eael-simple-menu eael-simple-menu-dropdown-animate-to-top eael-simple-menu-indicator eael-simple-menu-horizontal\"><li id=\"menu-item-15376\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15376\"><a href=\"https:\/\/www.whitehats.tech\/US\/data-security\/\">Data Foresight<\/a><\/li>\n<li id=\"menu-item-15377\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15377\"><a href=\"https:\/\/whitehats.tech\/US\/grc\/\">Compliance Foresight<\/a><\/li>\n<li id=\"menu-item-13464\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-13464\"><a href=\"https:\/\/whitehats.tech\/INDIA\/saas-grc\/\">Saas Model<\/a><\/li>\n<li id=\"menu-item-13465\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-13465\"><a href=\"https:\/\/whitehats.in\/privacy.html\">Privacy Policy<\/a><\/li>\n<\/ul>                <button class=\"eael-simple-menu-toggle\">\n                    <span class=\"sr-only \">Humberger Toggle Menu<\/span>\n                    <i aria-hidden=\"true\" class=\"fas fa-bars\"><\/i>                <\/button>\n            <\/div>\n            \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-34940d0 elementor-invisible\" data-id=\"34940d0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b43892 elementor-shape-circle elementor-grid-3 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"8b43892\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em));height:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:inline-flex;background-color:#69727d;align-items:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#69727d}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-threads{background-color:#000}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-x-twitter{background-color:#000}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-grow elementor-repeater-item-57144b8\" href=\"https:\/\/www.facebook.com\/whitehatscybertech\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-animation-grow elementor-repeater-item-6d46ef8\" href=\"https:\/\/twitter.com\/saleswhitehats\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 6.9199219 6 L 21.136719 26.726562 L 6.2285156 44 L 9.40625 44 L 22.544922 28.777344 L 32.986328 44 L 43 44 L 28.123047 22.3125 L 42.203125 6 L 39.027344 6 L 26.716797 20.261719 L 16.933594 6 L 6.9199219 6 z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-animation-grow elementor-repeater-item-ff19a98\" href=\"https:\/\/www.linkedin.com\/company\/whitehats-cybertech-pvt-ltd\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c48ef2 elementor-widget elementor-widget-text-editor\" data-id=\"2c48ef2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>A Premier Cybersecurity consulting and GRC Compliance Company<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Home About Product Data Foresight Compliance Foresight Saas Model ODAS Audit Management Policy Management Vulnerability Management Compliances ISO 27001:2022\u00a0 ISO 27701 ISO 22301 IRDA Compliance SEBI Compliance\u200b Contact News Home About Product Data Foresight Compliance Foresight Saas Model ODAS Audit Management Policy Management Vulnerability Management Compliances ISO 27001:2022\u00a0 ISO 27701 ISO 22301 IRDA Compliance SEBI Compliance\u200b Contact News Get a Demo SEBI Compliance SEBI (Securities and Exchange Board of India) has issued various guidelines and regulations related to cybersecurity compliance for the Indian securities market. The SEBI (Listing Obligations and Disclosure Requirements) Regulations, 2015, requires listed companies to adopt adequate cybersecurity measures and disclose the same to the stock exchanges. SEBI has taken various steps to ensure that the Indian securities market is adequately protected against cyber threats and that all stakeholders in the market are compliant with relevant cybersecurity regulations and guidelines. Connect us SEBI has released the Guidelines for Cyber Security and Cyber Resilience for all organizations registered with SEBI Key provisions and highlights of the cyber security and resilience framework Identification and Protection Mechanism Establish Governance Framework, Network and Security Controls, Data Security Controls, Application and Infrastructure Security Detection and Response Mechanism Continuous Monitoring and Reporting, Threat Detection and Analysis, Setting up Alerts Mechanisms Remediation and Recovery Create Remediation Priorities, Remediation Mechanisms, Internal and External Audits, BCP\/DR framework and activity Achieve your Cyber Security Compliance Compliance Management Integrated Vulnerability Management Integrated Privacy Framework ISO 27001:2022 ISO 22301 Risk Management CONTACT US A &#8211; 31, Sector &#8211; 4 Noida, UP 201301 India sales@whitehats.tech USEFUL LINKS Data Foresight Compliance Foresight Saas Model Privacy Policy Facebook Linkedin A Premier Cybersecurity consulting and GRC Compliance Company<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SEBI Compliance - Data Security - Data Privacy - Data Discovery<\/title>\n<meta name=\"description\" content=\"SEBI has issued various guidelines and regulations related to cybersecurity compliance for the Indian securities market, SEBI Compliance\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEBI Compliance - Data Security - Data Privacy - Data Discovery\" \/>\n<meta property=\"og:description\" content=\"SEBI has issued various guidelines and regulations related to cybersecurity compliance for the Indian securities market, SEBI Compliance\" \/>\n<meta property=\"og:url\" content=\"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/\" \/>\n<meta property=\"og:site_name\" content=\"Whitehats Technologies Inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/whitehatscybertech\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-13T09:01:10+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/whitehats-logo-1.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@saleswhitehats\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/\",\"url\":\"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/\",\"name\":\"SEBI Compliance - Data Security - Data Privacy - Data Discovery\",\"isPartOf\":{\"@id\":\"https:\/\/whitehats.tech\/INDIA\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/whitehats-logo-1.webp\",\"datePublished\":\"2023-11-14T10:37:22+00:00\",\"dateModified\":\"2024-02-13T09:01:10+00:00\",\"description\":\"SEBI has issued various guidelines and regulations related to cybersecurity compliance for the Indian securities market, SEBI Compliance\",\"breadcrumb\":{\"@id\":\"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/#primaryimage\",\"url\":\"http:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/whitehats-logo-1.webp\",\"contentUrl\":\"http:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/whitehats-logo-1.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/whitehats.tech\/INDIA\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEBI Compliance\u200b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/whitehats.tech\/INDIA\/#website\",\"url\":\"https:\/\/whitehats.tech\/INDIA\/\",\"name\":\"Whitehats Technologies Inc.\",\"description\":\"Cyber Security Automation Platform and Data Security Company\",\"publisher\":{\"@id\":\"https:\/\/whitehats.tech\/INDIA\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/whitehats.tech\/INDIA\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/whitehats.tech\/INDIA\/#organization\",\"name\":\"Whitehats Technology Inc.\",\"url\":\"https:\/\/whitehats.tech\/INDIA\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/whitehats.tech\/INDIA\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2022\/03\/Whitehats.png\",\"contentUrl\":\"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2022\/03\/Whitehats.png\",\"width\":445,\"height\":573,\"caption\":\"Whitehats Technology Inc.\"},\"image\":{\"@id\":\"https:\/\/whitehats.tech\/INDIA\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/whitehatscybertech\",\"https:\/\/x.com\/saleswhitehats\",\"https:\/\/www.linkedin.com\/company\/whitehats-cybertech-pvt-ltd\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SEBI Compliance - Data Security - Data Privacy - Data Discovery","description":"SEBI has issued various guidelines and regulations related to cybersecurity compliance for the Indian securities market, SEBI Compliance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/","og_locale":"en_US","og_type":"article","og_title":"SEBI Compliance - Data Security - Data Privacy - Data Discovery","og_description":"SEBI has issued various guidelines and regulations related to cybersecurity compliance for the Indian securities market, SEBI Compliance","og_url":"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/","og_site_name":"Whitehats Technologies Inc.","article_publisher":"https:\/\/www.facebook.com\/whitehatscybertech","article_modified_time":"2024-02-13T09:01:10+00:00","og_image":[{"url":"http:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/whitehats-logo-1.webp"}],"twitter_card":"summary_large_image","twitter_site":"@saleswhitehats","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/","url":"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/","name":"SEBI Compliance - Data Security - Data Privacy - Data Discovery","isPartOf":{"@id":"https:\/\/whitehats.tech\/INDIA\/#website"},"primaryImageOfPage":{"@id":"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/#primaryimage"},"image":{"@id":"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/#primaryimage"},"thumbnailUrl":"http:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/whitehats-logo-1.webp","datePublished":"2023-11-14T10:37:22+00:00","dateModified":"2024-02-13T09:01:10+00:00","description":"SEBI has issued various guidelines and regulations related to cybersecurity compliance for the Indian securities market, SEBI Compliance","breadcrumb":{"@id":"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/#primaryimage","url":"http:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/whitehats-logo-1.webp","contentUrl":"http:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2023\/11\/whitehats-logo-1.webp"},{"@type":"BreadcrumbList","@id":"http:\/\/whitehats.tech\/INDIA\/sebi-compliance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whitehats.tech\/INDIA\/"},{"@type":"ListItem","position":2,"name":"SEBI Compliance\u200b"}]},{"@type":"WebSite","@id":"https:\/\/whitehats.tech\/INDIA\/#website","url":"https:\/\/whitehats.tech\/INDIA\/","name":"Whitehats Technologies Inc.","description":"Cyber Security Automation Platform and Data Security Company","publisher":{"@id":"https:\/\/whitehats.tech\/INDIA\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whitehats.tech\/INDIA\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/whitehats.tech\/INDIA\/#organization","name":"Whitehats Technology Inc.","url":"https:\/\/whitehats.tech\/INDIA\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/whitehats.tech\/INDIA\/#\/schema\/logo\/image\/","url":"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2022\/03\/Whitehats.png","contentUrl":"https:\/\/whitehats.tech\/INDIA\/wp-content\/uploads\/2022\/03\/Whitehats.png","width":445,"height":573,"caption":"Whitehats Technology Inc."},"image":{"@id":"https:\/\/whitehats.tech\/INDIA\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/whitehatscybertech","https:\/\/x.com\/saleswhitehats","https:\/\/www.linkedin.com\/company\/whitehats-cybertech-pvt-ltd\/"]}]}},"_links":{"self":[{"href":"https:\/\/whitehats.tech\/INDIA\/wp-json\/wp\/v2\/pages\/13382"}],"collection":[{"href":"https:\/\/whitehats.tech\/INDIA\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whitehats.tech\/INDIA\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whitehats.tech\/INDIA\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/whitehats.tech\/INDIA\/wp-json\/wp\/v2\/comments?post=13382"}],"version-history":[{"count":6,"href":"https:\/\/whitehats.tech\/INDIA\/wp-json\/wp\/v2\/pages\/13382\/revisions"}],"predecessor-version":[{"id":15871,"href":"https:\/\/whitehats.tech\/INDIA\/wp-json\/wp\/v2\/pages\/13382\/revisions\/15871"}],"wp:attachment":[{"href":"https:\/\/whitehats.tech\/INDIA\/wp-json\/wp\/v2\/media?parent=13382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}